{"id":1769,"date":"2017-10-14T08:56:40","date_gmt":"2017-10-14T08:56:40","guid":{"rendered":"http:\/\/www.widherco.com\/?p=1769"},"modified":"2017-10-14T09:10:38","modified_gmt":"2017-10-14T09:10:38","slug":"ii-jornada-tecnica-widherco-haas","status":"publish","type":"post","link":"https:\/\/www.widherco.com\/es\/ii-jornada-tecnica-widherco-haas\/","title":{"rendered":"II JORNADA T\u00c9CNICA WIDHERCO: SISTEMAS DE MECANIZADO"},"content":{"rendered":"<p>Widherco celebra el \u00e9xito de la <strong>II Jornada T\u00e9cnica en Sistemas de Mecanizaci\u00f3n<\/strong>. Celebrada en las instalaciones de HAAS de Montcada i Reixac el pasado 28 de Septiembre y con la colaboraci\u00f3n de HAAS, IRAUPEN, WIDIA, ZOLLER y TECNOCIM.<\/p>\n<p>Se realiz\u00f3 la formaci\u00f3n de introducci\u00f3n en los sistemas de bru\u00f1ido y galeteado, escuadrado de alto rendimiento, torneado y fresado troco\u00efdal. Se presentaron las marcas WIDIA, URMA, ECOROLL y LANG TECHNIK, as\u00ed como las aplicaciones en sistemas CAD CAM de TECNOCIM y la medici\u00f3n de herramientas de la tecnolog\u00eda ZOLLER.<\/p>\n<p>Agradecemos a todos los colaboradores y asistentes su presencia.<\/p>","protected":false},"excerpt":{"rendered":"<p>Widherco celebra el \u00e9xito de la II Jornada T\u00e9cnica en Sistemas de Mecanizaci\u00f3n. Celebrada en las instalaciones de HAAS de Montcada i Reixac el pasado 28 de Septiembre y con la colaboraci\u00f3n de HAAS, IRAUPEN, WIDIA, ZOLLER y TECNOCIM. Se realiz\u00f3 la formaci\u00f3n de introducci\u00f3n en los sistemas de bru\u00f1ido y galeteado, escuadrado de alto [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1771,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false},"categories":[11],"tags":[16,12,14,17,15,13],"_links":{"self":[{"href":"https:\/\/www.widherco.com\/es\/wp-json\/wp\/v2\/posts\/1769"}],"collection":[{"href":"https:\/\/www.widherco.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.widherco.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.widherco.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.widherco.com\/es\/wp-json\/wp\/v2\/comments?post=1769"}],"version-history":[{"count":1,"href":"https:\/\/www.widherco.com\/es\/wp-json\/wp\/v2\/posts\/1769\/revisions"}],"predecessor-version":[{"id":1772,"href":"https:\/\/www.widherco.com\/es\/wp-json\/wp\/v2\/posts\/1769\/revisions\/1772"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.widherco.com\/es\/wp-json\/wp\/v2\/media\/1771"}],"wp:attachment":[{"href":"https:\/\/www.widherco.com\/es\/wp-json\/wp\/v2\/media?parent=1769"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.widherco.com\/es\/wp-json\/wp\/v2\/categories?post=1769"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.widherco.com\/es\/wp-json\/wp\/v2\/tags?post=1769"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}